{"id":7200,"date":"2024-05-08T08:56:19","date_gmt":"2024-05-08T06:56:19","guid":{"rendered":"https:\/\/www.pharmanutra.it\/it\/?p=7200"},"modified":"2024-05-08T08:56:19","modified_gmt":"2024-05-08T06:56:19","slug":"diatermia-e-acidi-grassi-cetilati-contro-il-dolore-muscolare","status":"publish","type":"post","link":"https:\/\/www.pharmanutra.it\/it\/diatermia-e-acidi-grassi-cetilati-contro-il-dolore-muscolare\/","title":{"rendered":"Diatermia e Acidi Grassi Cetilati (CFA): il binomio vincente contro il dolore muscolare"},"content":{"rendered":"<p>I\u00a0<strong>disturbi muscoloscheletrici<\/strong>, noti anche come <strong>disturbi da trauma cumulativo<\/strong>, si verificano quando la pressione applicata a questi tessuti supera la loro tolleranza allo sforzo.\u00a0Queste lesioni sono causate nel tempo dall&#8217;<strong>attivit\u00e0 fisica a carico dei muscoli, tendini, ossa e articolazioni <\/strong>e possono presentare complicazioni in una gamma di sintomi da lievi a gravi.<\/p>\n<p>Il dolore muscoloscheletrico pu\u00f2 essere limitato alla zona interessata o diffondersi ad altri distretti anatomici, compromettendo la qualit\u00e0 di vita di chi ne soffre.\u00a0Sebbene siano disponibili varie opzioni terapeutiche, alcune sono sfavorite a causa dei costi elevati e\/o degli effetti collaterali. Cerchiamo di capire quindi quali possono essere <strong>le migliori soluzioni contro il dolore muscoloscheletrico<\/strong>.<\/p>\n<h2>Come gestire il dolore causato da disturbi muscoloscheletrici?<\/h2>\n<p>Il dolore nei disturbi muscoloscheletrici viene attenuato grazie all\u2019utilizzo di farmaci, terapie strumentali e alla fisioterapia manuale da parte degli specialisti sanitari del settore.<\/p>\n<h3>Il trattamento farmacologico con antinfiammatori<\/h3>\n<p>Il <strong>trattamento farmacologico<\/strong> pi\u00f9 comune consiste nell\u2019applicazione di <strong>prodotti antinfiammatori topici<\/strong> sulla zona interessata. Tuttavia, la maggior parte delle molecole ad azione antinfiammatoria, a causa delle loro propriet\u00e0 chimico-fisiche, sono caratterizzate da un basso grado di assorbimento e penetrazione cutanea.<br \/>\n\u00c8 infatti noto che l\u2019assorbimento transdermico di una molecola avviene per movimento passivo ed \u00e8 dipendente da due principali variabili: la lipofilia della molecola in questione e la permeabilit\u00e0 intrinseca alle strutture cutanee. Per quanto riguarda il ruolo della lipofilia molecolare nella regolazione dell\u2019assorbimento attraverso le membrane cellulari \u00e8 ampiamente riconosciuto che maggiore \u00e8 la componente lipofila di una molecola, maggiore sar\u00e0 la sua facilit\u00e0 di assorbimento cutaneo. Al contrario, la presenza di gruppi idrofili ostacola il passaggio della molecola attraverso le membrane cellulari che compongono i tessuti cutanei.<\/p>\n<h3>La terapia strumentale TECAR<\/h3>\n<p>Tra i <strong>trattamenti strumentali<\/strong> utilizzati dagli operatori sanitari, troviamo la terapia di trasferimento energetico capacitivo e resistivo (Diatermia).\u00a0La <strong>terapia diatermica<\/strong>, chiamata anche con il nome di <strong>TECAR terapia<\/strong>, utilizza onde elettromagnetiche ad alta frequenza (da 0,3 a 1,2 MHz) e riduce gli spasmi e le contrazioni indotte dall&#8217;attivit\u00e0, migliora il flusso sanguigno e aiuta l&#8217;ossigenazione muscolare attraverso l&#8217;attivazione dell&#8217;emoglobina.\u00a0Pertanto, la terapia diatermica migliora la capacit\u00e0 naturale del corpo di riparare i tessuti e ridurre il dolore. Alcune evidenze scientifiche hanno rivelato che i pazienti sottoposti a questa terapia hanno avuto tempi di recupero pi\u00f9 brevi e hanno riacquistato prima la normale funzionalit\u00e0 degli arti.<\/p>\n<p>La diatermia \u00e8 <strong>un metodo complementare per il trattamento del dolore articolare<\/strong> ed \u00e8 uno strumento prezioso per i fisioterapisti e non interferisce con altre terapie.\u00a0Questa terapia viene utilizzata in numerosi campi della medicina, come ad esempio in ambito ortopedico, reumatico e in medicina estetica vascolare, ed il fatto che <strong>i tempi di recupero diminuiscono sensibilmente<\/strong> \u00e8 il suo principale vantaggio.\u00a0La sua principale applicazione terapeutica, come gi\u00e0 accennato sopra, trova maggiore collocazione in ambito fisioterapico, grazie alla quale genera un <strong>rapido miglioramento del processo infiammatorio acuto<\/strong> e permette il <strong>ritorno della forza muscolare<\/strong> rispetto ad altre terapie strumentali.<\/p>\n<h2>Gli Acidi Grassi Cetilati (CFA) nella gestione dei disturbi muscoloscheletrici<\/h2>\n<p>Un importante aiuto per la gestione della sintomatologia dolorosa dei disturbi muscoloscheletrici arriva dagli <a href=\"https:\/\/www.pharmanutra.it\/it\/esteri-cetilati\/\" target=\"_blank\" rel=\"noopener\">acidi grassi cetilati (CFA)<\/a> brevettati da PharmaNutra nei <a href=\"https:\/\/www.cetilar.com\/\" target=\"_blank\" rel=\"noopener\">prodotti a marchio Cetilar<sup>\u00ae<\/sup><\/a>.<strong>\u00a0I CFA sono un mix di acidi grassi di origine vegetale che hanno dimostrato essere efficaci nel ridurre il dolore muscolo-articolare e tendineo.<\/strong><\/p>\n<p>La linea dei prodotti Cetilar<sup>\u00ae<\/sup> per uso topico \u00e8 costituita da:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.pharmanutra.it\/it\/brand\/pharmanutra\/cetilar-crema\/\" target=\"_blank\" rel=\"noopener\">Cetilar<sup>\u00ae<\/sup> Crema<\/a><\/li>\n<li><a href=\"https:\/\/www.pharmanutra.it\/it\/brand\/pharmanutra\/cetilar-patch\/\" target=\"_blank\" rel=\"noopener\">Cetilar<sup>\u00ae<\/sup> Patch<\/a><\/li>\n<li><a href=\"https:\/\/www.pharmanutra.it\/it\/brand\/pharmanutra\/cetilar-tape\/\" target=\"_blank\" rel=\"noopener\">Cetilar<sup>\u00ae <\/sup>Tape<\/a><\/li>\n<\/ul>\n<p>Il <strong>meccanismo d\u2019azione dei CFA<\/strong> \u00e8 quello di favorire la lubrificazione articolare e quindi di migliorare meccanicamente il movimento dell\u2019articolazione, e grazie alla loro natura lipofila riescono ad aver un <strong>elevato assorbimento cutaneo<\/strong>, penetrando fino alla zona anatomica interessata dall\u2019infiammazione. Inoltre, \u00e8 stato dimostrato che l\u2019effetto benefico prodotto dai CFA, applicati tramite massaggio terapeutico in soggetti con sindrome dolorifica da osteoartrosi, potrebbe essere mediato dalla modificazione meccanica della membrana sinoviale, permettendo cos\u00ec la riduzione della sintomatologia dolorosa.<\/p>\n<h2>Acidi grassi cetilati in combinazione con la TECAR: evidenze scientifiche<\/h2>\n<p>Alcune evidenze scientifiche sono state condotte per valutare se la <strong>combinazione dei CFA per uso topico e terapia diatermica<\/strong> fosse utile per <strong>accelerare i tempi di guarigione<\/strong> in soggetti affetti da dolore muscoloscheletrico.<\/p>\n<p>Uno <strong>studio osservazionale<\/strong> <strong>presentato al Congresso Nazionale SIMFER (Societ\u00e0 Italiana di Medicina Fisica e Riabilitativa) 2020<\/strong> dalla dr.ssa Valderetti, ha coinvolto 31 soggetti affetti da dolore muscolare, osteo-articolare o tendineo localizzato in vari distretti in una serie di sedute di diatermia (5 o 10 sedute) alla fine delle quali era prevista l\u2019applicazione di 5 grammi di Cetilar<sup>\u00ae<\/sup> Crema, tramite massaggio manuale da parte dell\u2019operatore sanitario. Ai pazienti veniva chiesto di indicare il dolore su una scala analogica VAS (Visual Analogue Scale), uno dei parametri pi\u00f9 utilizzati per stimare l\u2019intensit\u00e0 del dolore e per stabilire l\u2019entit\u00e0 di sollievo dal dolore, prima di iniziare il trattamento, dopo 5 sedute (trattamento corto) o dopo 10 sedute (trattamento lungo).<\/p>\n<p>Sia i pazienti che hanno effettuato il trattamento corto, che quelli che hanno effettuato il trattamento lungo, hanno riportato una riduzione significativa del dolore. I risultati di questo studio osservazionale confermano che <strong>l\u2019applicazione di Cetilar<sup>\u00ae<\/sup> Crema dopo le sedute di diatermia \u00e8 una combinazione vincente nella riduzione del dolore<\/strong> nelle situazioni che pi\u00f9 comunemente colpiscono la popolazione di una certa et\u00e0 e che difficilmente vengono risolte in cos\u00ec poco tempo.<\/p>\n<p>Questo importante risultato ha permesso di stabilire che il trattamento combinato della diatermia seguita dall\u2019applicazione topica dei CFA ha dimostrato di essere <strong>efficace nella riduzione del dolore muscolare, articolare e tendineo<\/strong>.<\/p>\n<p>In conclusione, l&#8217;applicazione di Cetilar<sup>\u00ae<\/sup> Crema dopo ogni seduta di diatermia \u00e8 stata considerata efficace, curativa e l\u2019utilizzo di questa crema contemporaneamente alla TECAR non ha alcun effetto dannoso sul macchinario durante la sessione di trattamento.<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p><strong>BIBLIOGRAFIA<\/strong><\/p>\n<ol>\n<li>Vahdatpour B., et al.; Effects of Transfer Energy Capacitive and Resistive On Musculoskeletal Pain: A Systematic Review and Meta-Analysis: Galen Med J. 2022 Nov 17;11:e2407.<\/li>\n<li>Visconti L., et al.; Comparison of the effectiveness of manual massage, long-wave diathermy, and sham long-wave diathermy for the management of delayed-onset muscle soreness: a randomized controlled trial.Arch Physiother. 2020 Jan 15;10:1.<\/li>\n<li>Valderetti N., et al.; Effect of combined diathermy treatment with topic application of a cream based on cetylated fatty acids (CFAs) in pain reduction in average elderly patients. SIMFER Congress; 2020 Dec 2-4;<\/li>\n<li>Ariani A., et al.; Short-Term Effect of Topical Cetylated Fatty Acid on Early and Advanced Knee Osteoarthritis: A Multi-Center Study. Arch Rheumatol. 2018 Mar 23;33(4):438-442.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I\u00a0disturbi muscoloscheletrici, noti anche come disturbi da trauma cumulativo, si verificano quando la pressione applicata a questi tessuti supera la loro tolleranza allo sforzo.\u00a0Queste lesioni sono causate nel tempo dall&#8217;attivit\u00e0 fisica a carico dei muscoli, tendini, ossa e articolazioni e possono presentare complicazioni in una gamma di sintomi da lievi a gravi. Il dolore muscoloscheletrico [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":7201,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[101],"tags":[121,131],"anno_documento":[79],"class_list":["post-7200","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-muscoli-e-articolazioni","tag-medicina-sportiva","tag-ortopedia","anno_documento-79"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Diatermia e Acidi Grassi Cetilati (CFA) contro il dolore muscolare<\/title>\n<meta name=\"description\" content=\"L&#039;uso combinato di diatermia e Acidi Grassi Cetilati (CFA) \u00e8 risultato efficace nella riduzione del dolore muscolare, articolare e tendineo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pharmanutra.it\/it\/diatermia-e-acidi-grassi-cetilati-contro-il-dolore-muscolare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diatermia e Acidi Grassi Cetilati (CFA) contro il dolore muscolare\" \/>\n<meta property=\"og:description\" content=\"L&#039;uso combinato di diatermia e Acidi Grassi Cetilati (CFA) \u00e8 risultato efficace nella riduzione del dolore muscolare, articolare e tendineo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pharmanutra.it\/it\/diatermia-e-acidi-grassi-cetilati-contro-il-dolore-muscolare\/\" \/>\n<meta property=\"og:site_name\" content=\"pharmanutra.it\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-08T06:56:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pharmanutra.it\/wp-content\/uploads\/2024\/05\/CFA-e-tecar-terapia.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Silvia Rigotto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Silvia Rigotto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.pharmanutra.it\\\/it\\\/diatermia-e-acidi-grassi-cetilati-contro-il-dolore-muscolare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pharmanutra.it\\\/it\\\/diatermia-e-acidi-grassi-cetilati-contro-il-dolore-muscolare\\\/\"},\"author\":{\"name\":\"Silvia Rigotto\",\"@id\":\"https:\\\/\\\/www.pharmanutra.it\\\/it\\\/#\\\/schema\\\/person\\\/e167594e059fd908b48f144590a46ccd\"},\"headline\":\"Diatermia e Acidi Grassi Cetilati (CFA): il binomio vincente contro il dolore muscolare\",\"datePublished\":\"2024-05-08T06:56:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.pharmanutra.it\\\/it\\\/diatermia-e-acidi-grassi-cetilati-contro-il-dolore-muscolare\\\/\"},\"wordCount\":1063,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.pharmanutra.it\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pharmanutra.it\\\/it\\\/diatermia-e-acidi-grassi-cetilati-contro-il-dolore-muscolare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pharmanutra.it\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/CFA-e-tecar-terapia.png\",\"keywords\":[\"Medicina sportiva\",\"Ortopedia\"],\"articleSection\":[\"Muscoli e articolazioni\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.pharmanutra.it\\\/it\\\/diatermia-e-acidi-grassi-cetilati-contro-il-dolore-muscolare\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pharmanutra.it\\\/it\\\/diatermia-e-acidi-grassi-cetilati-contro-il-dolore-muscolare\\\/\",\"url\":\"https:\\\/\\\/www.pharmanutra.it\\\/it\\\/diatermia-e-acidi-grassi-cetilati-contro-il-dolore-muscolare\\\/\",\"name\":\"Diatermia e Acidi Grassi Cetilati (CFA) contro il dolore muscolare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pharmanutra.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.pharmanutra.it\\\/it\\\/diatermia-e-acidi-grassi-cetilati-contro-il-dolore-muscolare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pharmanutra.it\\\/it\\\/diatermia-e-acidi-grassi-cetilati-contro-il-dolore-muscolare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pharmanutra.it\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/CFA-e-tecar-terapia.png\",\"datePublished\":\"2024-05-08T06:56:19+00:00\",\"description\":\"L'uso combinato di diatermia e Acidi Grassi Cetilati (CFA) \u00e8 risultato efficace nella riduzione del dolore muscolare, articolare e tendineo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pharmanutra.it\\\/it\\\/diatermia-e-acidi-grassi-cetilati-contro-il-dolore-muscolare\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pharmanutra.it\\\/it\\\/diatermia-e-acidi-grassi-cetilati-contro-il-dolore-muscolare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.pharmanutra.it\\\/it\\\/diatermia-e-acidi-grassi-cetilati-contro-il-dolore-muscolare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.pharmanutra.it\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/CFA-e-tecar-terapia.png\",\"contentUrl\":\"https:\\\/\\\/www.pharmanutra.it\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/CFA-e-tecar-terapia.png\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pharmanutra.it\\\/it\\\/diatermia-e-acidi-grassi-cetilati-contro-il-dolore-muscolare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pharmanutra.it\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diatermia e Acidi Grassi Cetilati (CFA): il binomio vincente contro il dolore muscolare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pharmanutra.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.pharmanutra.it\\\/it\\\/\",\"name\":\"pharmanutra.it\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.pharmanutra.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pharmanutra.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.pharmanutra.it\\\/it\\\/#organization\",\"name\":\"pharmanutra.it\",\"url\":\"https:\\\/\\\/www.pharmanutra.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.pharmanutra.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.pharmanutra.it\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/PHN_LOGO2020color.png\",\"contentUrl\":\"https:\\\/\\\/www.pharmanutra.it\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/PHN_LOGO2020color.png\",\"width\":1856,\"height\":210,\"caption\":\"pharmanutra.it\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pharmanutra.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.pharmanutra.it\\\/it\\\/#\\\/schema\\\/person\\\/e167594e059fd908b48f144590a46ccd\",\"name\":\"Silvia Rigotto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/74de320c47466acb3ce41afd90e724ba09607692eb64df19e5d1a3518ea9984c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/74de320c47466acb3ce41afd90e724ba09607692eb64df19e5d1a3518ea9984c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/74de320c47466acb3ce41afd90e724ba09607692eb64df19e5d1a3518ea9984c?s=96&d=mm&r=g\",\"caption\":\"Silvia Rigotto\"},\"url\":\"https:\\\/\\\/www.pharmanutra.it\\\/it\\\/author\\\/s-rigotto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diatermia e Acidi Grassi Cetilati (CFA) contro il dolore muscolare","description":"L'uso combinato di diatermia e Acidi Grassi Cetilati (CFA) \u00e8 risultato efficace nella riduzione del dolore muscolare, articolare e tendineo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pharmanutra.it\/it\/diatermia-e-acidi-grassi-cetilati-contro-il-dolore-muscolare\/","og_locale":"it_IT","og_type":"article","og_title":"Diatermia e Acidi Grassi Cetilati (CFA) contro il dolore muscolare","og_description":"L'uso combinato di diatermia e Acidi Grassi Cetilati (CFA) \u00e8 risultato efficace nella riduzione del dolore muscolare, articolare e tendineo.","og_url":"https:\/\/www.pharmanutra.it\/it\/diatermia-e-acidi-grassi-cetilati-contro-il-dolore-muscolare\/","og_site_name":"pharmanutra.it","article_published_time":"2024-05-08T06:56:19+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.pharmanutra.it\/wp-content\/uploads\/2024\/05\/CFA-e-tecar-terapia.png","type":"image\/png"}],"author":"Silvia Rigotto","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Silvia Rigotto","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pharmanutra.it\/it\/diatermia-e-acidi-grassi-cetilati-contro-il-dolore-muscolare\/#article","isPartOf":{"@id":"https:\/\/www.pharmanutra.it\/it\/diatermia-e-acidi-grassi-cetilati-contro-il-dolore-muscolare\/"},"author":{"name":"Silvia Rigotto","@id":"https:\/\/www.pharmanutra.it\/it\/#\/schema\/person\/e167594e059fd908b48f144590a46ccd"},"headline":"Diatermia e Acidi Grassi Cetilati (CFA): il binomio vincente contro il dolore muscolare","datePublished":"2024-05-08T06:56:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pharmanutra.it\/it\/diatermia-e-acidi-grassi-cetilati-contro-il-dolore-muscolare\/"},"wordCount":1063,"commentCount":0,"publisher":{"@id":"https:\/\/www.pharmanutra.it\/it\/#organization"},"image":{"@id":"https:\/\/www.pharmanutra.it\/it\/diatermia-e-acidi-grassi-cetilati-contro-il-dolore-muscolare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pharmanutra.it\/wp-content\/uploads\/2024\/05\/CFA-e-tecar-terapia.png","keywords":["Medicina sportiva","Ortopedia"],"articleSection":["Muscoli e articolazioni"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pharmanutra.it\/it\/diatermia-e-acidi-grassi-cetilati-contro-il-dolore-muscolare\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pharmanutra.it\/it\/diatermia-e-acidi-grassi-cetilati-contro-il-dolore-muscolare\/","url":"https:\/\/www.pharmanutra.it\/it\/diatermia-e-acidi-grassi-cetilati-contro-il-dolore-muscolare\/","name":"Diatermia e Acidi Grassi Cetilati (CFA) contro il dolore muscolare","isPartOf":{"@id":"https:\/\/www.pharmanutra.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pharmanutra.it\/it\/diatermia-e-acidi-grassi-cetilati-contro-il-dolore-muscolare\/#primaryimage"},"image":{"@id":"https:\/\/www.pharmanutra.it\/it\/diatermia-e-acidi-grassi-cetilati-contro-il-dolore-muscolare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pharmanutra.it\/wp-content\/uploads\/2024\/05\/CFA-e-tecar-terapia.png","datePublished":"2024-05-08T06:56:19+00:00","description":"L'uso combinato di diatermia e Acidi Grassi Cetilati (CFA) \u00e8 risultato efficace nella riduzione del dolore muscolare, articolare e tendineo.","breadcrumb":{"@id":"https:\/\/www.pharmanutra.it\/it\/diatermia-e-acidi-grassi-cetilati-contro-il-dolore-muscolare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pharmanutra.it\/it\/diatermia-e-acidi-grassi-cetilati-contro-il-dolore-muscolare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.pharmanutra.it\/it\/diatermia-e-acidi-grassi-cetilati-contro-il-dolore-muscolare\/#primaryimage","url":"https:\/\/www.pharmanutra.it\/wp-content\/uploads\/2024\/05\/CFA-e-tecar-terapia.png","contentUrl":"https:\/\/www.pharmanutra.it\/wp-content\/uploads\/2024\/05\/CFA-e-tecar-terapia.png","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.pharmanutra.it\/it\/diatermia-e-acidi-grassi-cetilati-contro-il-dolore-muscolare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pharmanutra.it\/it\/"},{"@type":"ListItem","position":2,"name":"Diatermia e Acidi Grassi Cetilati (CFA): il binomio vincente contro il dolore muscolare"}]},{"@type":"WebSite","@id":"https:\/\/www.pharmanutra.it\/it\/#website","url":"https:\/\/www.pharmanutra.it\/it\/","name":"pharmanutra.it","description":"","publisher":{"@id":"https:\/\/www.pharmanutra.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pharmanutra.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.pharmanutra.it\/it\/#organization","name":"pharmanutra.it","url":"https:\/\/www.pharmanutra.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.pharmanutra.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.pharmanutra.it\/wp-content\/uploads\/2025\/09\/PHN_LOGO2020color.png","contentUrl":"https:\/\/www.pharmanutra.it\/wp-content\/uploads\/2025\/09\/PHN_LOGO2020color.png","width":1856,"height":210,"caption":"pharmanutra.it"},"image":{"@id":"https:\/\/www.pharmanutra.it\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.pharmanutra.it\/it\/#\/schema\/person\/e167594e059fd908b48f144590a46ccd","name":"Silvia Rigotto","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/74de320c47466acb3ce41afd90e724ba09607692eb64df19e5d1a3518ea9984c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/74de320c47466acb3ce41afd90e724ba09607692eb64df19e5d1a3518ea9984c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/74de320c47466acb3ce41afd90e724ba09607692eb64df19e5d1a3518ea9984c?s=96&d=mm&r=g","caption":"Silvia Rigotto"},"url":"https:\/\/www.pharmanutra.it\/it\/author\/s-rigotto\/"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/www.pharmanutra.it\/it\/wp-json\/wp\/v2\/posts\/7200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pharmanutra.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pharmanutra.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pharmanutra.it\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pharmanutra.it\/it\/wp-json\/wp\/v2\/comments?post=7200"}],"version-history":[{"count":0,"href":"https:\/\/www.pharmanutra.it\/it\/wp-json\/wp\/v2\/posts\/7200\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pharmanutra.it\/it\/wp-json\/wp\/v2\/media\/7201"}],"wp:attachment":[{"href":"https:\/\/www.pharmanutra.it\/it\/wp-json\/wp\/v2\/media?parent=7200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pharmanutra.it\/it\/wp-json\/wp\/v2\/categories?post=7200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pharmanutra.it\/it\/wp-json\/wp\/v2\/tags?post=7200"},{"taxonomy":"anno_documento","embeddable":true,"href":"https:\/\/www.pharmanutra.it\/it\/wp-json\/wp\/v2\/anno_documento?post=7200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}